{"id":2909,"date":"2021-03-23T22:13:34","date_gmt":"2021-03-23T21:13:34","guid":{"rendered":"http:\/\/www.crislermusic.com\/?post_type=download&#038;p=2909"},"modified":"2021-03-23T22:13:34","modified_gmt":"2021-03-23T21:13:34","slug":"sergio-bassi-cavallo-pazzo","status":"publish","type":"download","link":"https:\/\/www.crislermusic.com\/index.php\/downloads\/sergio-bassi-cavallo-pazzo\/","title":{"rendered":"SERGIO BASSI &#8211; CAVALLO PAZZO"},"content":{"rendered":"<div id=\"attachment_2921\" style=\"width: 310px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-2921\" class=\"size-medium wp-image-2921\" src=\"https:\/\/www.crislermusic.com\/wp-content\/uploads\/edd\/2021\/03\/Sergio-Bassi-Cavallo-pazzo_500pxl-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.crislermusic.com\/wp-content\/uploads\/edd\/2021\/03\/Sergio-Bassi-Cavallo-pazzo_500pxl-300x300.jpg 300w, https:\/\/www.crislermusic.com\/wp-content\/uploads\/edd\/2021\/03\/Sergio-Bassi-Cavallo-pazzo_500pxl-150x150.jpg 150w, https:\/\/www.crislermusic.com\/wp-content\/uploads\/edd\/2021\/03\/Sergio-Bassi-Cavallo-pazzo_500pxl-350x350.jpg 350w, https:\/\/www.crislermusic.com\/wp-content\/uploads\/edd\/2021\/03\/Sergio-Bassi-Cavallo-pazzo_500pxl-100x100.jpg 100w, https:\/\/www.crislermusic.com\/wp-content\/uploads\/edd\/2021\/03\/Sergio-Bassi-Cavallo-pazzo_500pxl.jpg 500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-2921\" class=\"wp-caption-text\">SERGIO BASSI &#8211; CAVALLO PAZZO<\/p><\/div>\n<!--[if lt IE 9]><script>document.createElement('audio');<\/script><![endif]-->\n\t<div class=\"wp-playlist wp-audio-playlist wp-playlist-light\">\n\t\t\t<div class=\"wp-playlist-current-item\"><\/div>\n\t\t<audio controls=\"controls\" preload=\"none\" width=\"748\"\n\t\t\t><\/audio>\n\t<div class=\"wp-playlist-next\"><\/div>\n\t<div class=\"wp-playlist-prev\"><\/div>\n\t<noscript>\n\t<ol>\n\t\t<li><a href='https:\/\/www.crislermusic.com\/wp-content\/uploads\/edd\/2021\/03\/01-Brando_.mp3'>01 Brando_<\/a><\/li><li><a href='https:\/\/www.crislermusic.com\/wp-content\/uploads\/edd\/2021\/03\/02-Cavallo-Pazzo_.mp3'>02 Cavallo Pazzo_<\/a><\/li><li><a href='https:\/\/www.crislermusic.com\/wp-content\/uploads\/edd\/2021\/03\/03-Amos_.mp3'>03 Amos_<\/a><\/li><li><a href='https:\/\/www.crislermusic.com\/wp-content\/uploads\/edd\/2021\/03\/04-Ulisse_.mp3'>04 Ulisse_<\/a><\/li><li><a href='https:\/\/www.crislermusic.com\/wp-content\/uploads\/edd\/2021\/03\/05-Canzone-D-Amore_.mp3'>05 Canzone D' Amore_<\/a><\/li><li><a href='https:\/\/www.crislermusic.com\/wp-content\/uploads\/edd\/2021\/03\/06-Il-Conte-Max_.mp3'>06 Il Conte Max_<\/a><\/li><li><a href='https:\/\/www.crislermusic.com\/wp-content\/uploads\/edd\/2021\/03\/07-Nostradamus_.mp3'>07 Nostradamus_<\/a><\/li><li><a href='https:\/\/www.crislermusic.com\/wp-content\/uploads\/edd\/2021\/03\/08-Vorrei-Fermare-Il-Tempo_.mp3'>08 Vorrei Fermare Il Tempo_<\/a><\/li><li><a href='https:\/\/www.crislermusic.com\/wp-content\/uploads\/edd\/2021\/03\/09-Framavi_.mp3'>09 Framavi_<\/a><\/li><li><a href='https:\/\/www.crislermusic.com\/wp-content\/uploads\/edd\/2021\/03\/10-Cremona_.mp3'>10 Cremona_<\/a><\/li><li><a href='https:\/\/www.crislermusic.com\/wp-content\/uploads\/edd\/2021\/03\/11-Il-Mantovano-Volante_.mp3'>11 Il Mantovano Volante_<\/a><\/li><li><a href='https:\/\/www.crislermusic.com\/wp-content\/uploads\/edd\/2021\/03\/12-Farfalla_.mp3'>12 Farfalla_<\/a><\/li><li><a href='https:\/\/www.crislermusic.com\/wp-content\/uploads\/edd\/2021\/03\/13-Ci-Vuole-Solo-Un-Minuto_.mp3'>13 Ci Vuole Solo Un Minuto_<\/a><\/li><li><a href='https:\/\/www.crislermusic.com\/wp-content\/uploads\/edd\/2021\/03\/14-NOI_.mp3'>14 NOI_<\/a><\/li>\t<\/ol>\n\t<\/noscript>\n\t<script type=\"application\/json\" class=\"wp-playlist-script\">{\"type\":\"audio\",\"tracklist\":true,\"tracknumbers\":true,\"images\":true,\"artists\":true,\"tracks\":[{\"src\":\"https:\\\/\\\/www.crislermusic.com\\\/wp-content\\\/uploads\\\/edd\\\/2021\\\/03\\\/01-Brando_.mp3\",\"type\":\"audio\\\/mpeg\",\"title\":\"01 Brando_\",\"caption\":\"\",\"description\":\"\\\"01 Brando_\\\". Genere: Blues.\",\"meta\":{\"genre\":\"Blues\",\"length_formatted\":\"1:54\"},\"image\":{\"src\":\"https:\\\/\\\/www.crislermusic.com\\\/wp-includes\\\/images\\\/media\\\/audio.svg\",\"width\":48,\"height\":64},\"thumb\":{\"src\":\"https:\\\/\\\/www.crislermusic.com\\\/wp-includes\\\/images\\\/media\\\/audio.svg\",\"width\":48,\"height\":64}},{\"src\":\"https:\\\/\\\/www.crislermusic.com\\\/wp-content\\\/uploads\\\/edd\\\/2021\\\/03\\\/02-Cavallo-Pazzo_.mp3\",\"type\":\"audio\\\/mpeg\",\"title\":\"02 Cavallo Pazzo_\",\"caption\":\"\",\"description\":\"\\\"02 Cavallo Pazzo_\\\". Genere: Blues.\",\"meta\":{\"genre\":\"Blues\",\"length_formatted\":\"1:53\"},\"image\":{\"src\":\"https:\\\/\\\/www.crislermusic.com\\\/wp-includes\\\/images\\\/media\\\/audio.svg\",\"width\":48,\"height\":64},\"thumb\":{\"src\":\"https:\\\/\\\/www.crislermusic.com\\\/wp-includes\\\/images\\\/media\\\/audio.svg\",\"width\":48,\"height\":64}},{\"src\":\"https:\\\/\\\/www.crislermusic.com\\\/wp-content\\\/uploads\\\/edd\\\/2021\\\/03\\\/03-Amos_.mp3\",\"type\":\"audio\\\/mpeg\",\"title\":\"03 Amos_\",\"caption\":\"\",\"description\":\"\\\"03 Amos_\\\". Genere: Blues.\",\"meta\":{\"genre\":\"Blues\",\"length_formatted\":\"1:52\"},\"image\":{\"src\":\"https:\\\/\\\/www.crislermusic.com\\\/wp-includes\\\/images\\\/media\\\/audio.svg\",\"width\":48,\"height\":64},\"thumb\":{\"src\":\"https:\\\/\\\/www.crislermusic.com\\\/wp-includes\\\/images\\\/media\\\/audio.svg\",\"width\":48,\"height\":64}},{\"src\":\"https:\\\/\\\/www.crislermusic.com\\\/wp-content\\\/uploads\\\/edd\\\/2021\\\/03\\\/04-Ulisse_.mp3\",\"type\":\"audio\\\/mpeg\",\"title\":\"04 Ulisse_\",\"caption\":\"\",\"description\":\"\\\"04 Ulisse_\\\". Genere: Blues.\",\"meta\":{\"genre\":\"Blues\",\"length_formatted\":\"1:50\"},\"image\":{\"src\":\"https:\\\/\\\/www.crislermusic.com\\\/wp-includes\\\/images\\\/media\\\/audio.svg\",\"width\":48,\"height\":64},\"thumb\":{\"src\":\"https:\\\/\\\/www.crislermusic.com\\\/wp-includes\\\/images\\\/media\\\/audio.svg\",\"width\":48,\"height\":64}},{\"src\":\"https:\\\/\\\/www.crislermusic.com\\\/wp-content\\\/uploads\\\/edd\\\/2021\\\/03\\\/05-Canzone-D-Amore_.mp3\",\"type\":\"audio\\\/mpeg\",\"title\":\"05 Canzone D' Amore_\",\"caption\":\"\",\"description\":\"\\\"05 Canzone D' Amore_\\\". Genere: Blues.\",\"meta\":{\"genre\":\"Blues\",\"length_formatted\":\"1:54\"},\"image\":{\"src\":\"https:\\\/\\\/www.crislermusic.com\\\/wp-includes\\\/images\\\/media\\\/audio.svg\",\"width\":48,\"height\":64},\"thumb\":{\"src\":\"https:\\\/\\\/www.crislermusic.com\\\/wp-includes\\\/images\\\/media\\\/audio.svg\",\"width\":48,\"height\":64}},{\"src\":\"https:\\\/\\\/www.crislermusic.com\\\/wp-content\\\/uploads\\\/edd\\\/2021\\\/03\\\/06-Il-Conte-Max_.mp3\",\"type\":\"audio\\\/mpeg\",\"title\":\"06 Il Conte Max_\",\"caption\":\"\",\"description\":\"\\\"06 Il Conte Max_\\\". Genere: Blues.\",\"meta\":{\"genre\":\"Blues\",\"length_formatted\":\"1:54\"},\"image\":{\"src\":\"https:\\\/\\\/www.crislermusic.com\\\/wp-includes\\\/images\\\/media\\\/audio.svg\",\"width\":48,\"height\":64},\"thumb\":{\"src\":\"https:\\\/\\\/www.crislermusic.com\\\/wp-includes\\\/images\\\/media\\\/audio.svg\",\"width\":48,\"height\":64}},{\"src\":\"https:\\\/\\\/www.crislermusic.com\\\/wp-content\\\/uploads\\\/edd\\\/2021\\\/03\\\/07-Nostradamus_.mp3\",\"type\":\"audio\\\/mpeg\",\"title\":\"07 Nostradamus_\",\"caption\":\"\",\"description\":\"\\\"07 Nostradamus_\\\". Genere: Blues.\",\"meta\":{\"genre\":\"Blues\",\"length_formatted\":\"1:55\"},\"image\":{\"src\":\"https:\\\/\\\/www.crislermusic.com\\\/wp-includes\\\/images\\\/media\\\/audio.svg\",\"width\":48,\"height\":64},\"thumb\":{\"src\":\"https:\\\/\\\/www.crislermusic.com\\\/wp-includes\\\/images\\\/media\\\/audio.svg\",\"width\":48,\"height\":64}},{\"src\":\"https:\\\/\\\/www.crislermusic.com\\\/wp-content\\\/uploads\\\/edd\\\/2021\\\/03\\\/08-Vorrei-Fermare-Il-Tempo_.mp3\",\"type\":\"audio\\\/mpeg\",\"title\":\"08 Vorrei Fermare Il Tempo_\",\"caption\":\"\",\"description\":\"\\\"08 Vorrei Fermare Il Tempo_\\\". Genere: Blues.\",\"meta\":{\"genre\":\"Blues\",\"length_formatted\":\"1:52\"},\"image\":{\"src\":\"https:\\\/\\\/www.crislermusic.com\\\/wp-includes\\\/images\\\/media\\\/audio.svg\",\"width\":48,\"height\":64},\"thumb\":{\"src\":\"https:\\\/\\\/www.crislermusic.com\\\/wp-includes\\\/images\\\/media\\\/audio.svg\",\"width\":48,\"height\":64}},{\"src\":\"https:\\\/\\\/www.crislermusic.com\\\/wp-content\\\/uploads\\\/edd\\\/2021\\\/03\\\/09-Framavi_.mp3\",\"type\":\"audio\\\/mpeg\",\"title\":\"09 Framavi_\",\"caption\":\"\",\"description\":\"\\\"09 Framavi_\\\". Genere: Blues.\",\"meta\":{\"genre\":\"Blues\",\"length_formatted\":\"1:53\"},\"image\":{\"src\":\"https:\\\/\\\/www.crislermusic.com\\\/wp-includes\\\/images\\\/media\\\/audio.svg\",\"width\":48,\"height\":64},\"thumb\":{\"src\":\"https:\\\/\\\/www.crislermusic.com\\\/wp-includes\\\/images\\\/media\\\/audio.svg\",\"width\":48,\"height\":64}},{\"src\":\"https:\\\/\\\/www.crislermusic.com\\\/wp-content\\\/uploads\\\/edd\\\/2021\\\/03\\\/10-Cremona_.mp3\",\"type\":\"audio\\\/mpeg\",\"title\":\"10 Cremona_\",\"caption\":\"\",\"description\":\"\\\"10 Cremona_\\\". Genere: Blues.\",\"meta\":{\"genre\":\"Blues\",\"length_formatted\":\"1:53\"},\"image\":{\"src\":\"https:\\\/\\\/www.crislermusic.com\\\/wp-includes\\\/images\\\/media\\\/audio.svg\",\"width\":48,\"height\":64},\"thumb\":{\"src\":\"https:\\\/\\\/www.crislermusic.com\\\/wp-includes\\\/images\\\/media\\\/audio.svg\",\"width\":48,\"height\":64}},{\"src\":\"https:\\\/\\\/www.crislermusic.com\\\/wp-content\\\/uploads\\\/edd\\\/2021\\\/03\\\/11-Il-Mantovano-Volante_.mp3\",\"type\":\"audio\\\/mpeg\",\"title\":\"11 Il Mantovano Volante_\",\"caption\":\"\",\"description\":\"\\\"11 Il Mantovano Volante_\\\". Genere: Blues.\",\"meta\":{\"genre\":\"Blues\",\"length_formatted\":\"1:51\"},\"image\":{\"src\":\"https:\\\/\\\/www.crislermusic.com\\\/wp-includes\\\/images\\\/media\\\/audio.svg\",\"width\":48,\"height\":64},\"thumb\":{\"src\":\"https:\\\/\\\/www.crislermusic.com\\\/wp-includes\\\/images\\\/media\\\/audio.svg\",\"width\":48,\"height\":64}},{\"src\":\"https:\\\/\\\/www.crislermusic.com\\\/wp-content\\\/uploads\\\/edd\\\/2021\\\/03\\\/12-Farfalla_.mp3\",\"type\":\"audio\\\/mpeg\",\"title\":\"12 Farfalla_\",\"caption\":\"\",\"description\":\"\\\"12 Farfalla_\\\". Genere: Blues.\",\"meta\":{\"genre\":\"Blues\",\"length_formatted\":\"1:55\"},\"image\":{\"src\":\"https:\\\/\\\/www.crislermusic.com\\\/wp-includes\\\/images\\\/media\\\/audio.svg\",\"width\":48,\"height\":64},\"thumb\":{\"src\":\"https:\\\/\\\/www.crislermusic.com\\\/wp-includes\\\/images\\\/media\\\/audio.svg\",\"width\":48,\"height\":64}},{\"src\":\"https:\\\/\\\/www.crislermusic.com\\\/wp-content\\\/uploads\\\/edd\\\/2021\\\/03\\\/13-Ci-Vuole-Solo-Un-Minuto_.mp3\",\"type\":\"audio\\\/mpeg\",\"title\":\"13 Ci Vuole Solo Un Minuto_\",\"caption\":\"\",\"description\":\"\\\"13 Ci Vuole Solo Un Minuto_\\\". Genere: Blues.\",\"meta\":{\"genre\":\"Blues\",\"length_formatted\":\"1:53\"},\"image\":{\"src\":\"https:\\\/\\\/www.crislermusic.com\\\/wp-includes\\\/images\\\/media\\\/audio.svg\",\"width\":48,\"height\":64},\"thumb\":{\"src\":\"https:\\\/\\\/www.crislermusic.com\\\/wp-includes\\\/images\\\/media\\\/audio.svg\",\"width\":48,\"height\":64}},{\"src\":\"https:\\\/\\\/www.crislermusic.com\\\/wp-content\\\/uploads\\\/edd\\\/2021\\\/03\\\/14-NOI_.mp3\",\"type\":\"audio\\\/mpeg\",\"title\":\"14 NOI_\",\"caption\":\"\",\"description\":\"\\\"14 NOI_\\\". Genere: Blues.\",\"meta\":{\"genre\":\"Blues\",\"length_formatted\":\"1:48\"},\"image\":{\"src\":\"https:\\\/\\\/www.crislermusic.com\\\/wp-includes\\\/images\\\/media\\\/audio.svg\",\"width\":48,\"height\":64},\"thumb\":{\"src\":\"https:\\\/\\\/www.crislermusic.com\\\/wp-includes\\\/images\\\/media\\\/audio.svg\",\"width\":48,\"height\":64}}]}<\/script>\n<\/div>\n\t\n","protected":false},"excerpt":{"rendered":"<p> <a class=\"continue-reading-link\" href=\"https:\/\/www.crislermusic.com\/index.php\/downloads\/sergio-bassi-cavallo-pazzo\/\">Continue reading<\/a><\/p>\n<p> <a class=\"continue-reading-link\" href=\"https:\/\/www.crislermusic.com\/index.php\/downloads\/sergio-bassi-cavallo-pazzo\/\">Continue reading<\/a><\/p>\n","protected":false},"author":1,"featured_media":2921,"template":"","edd-categories":[22],"edd-tags":[],"_links":{"self":[{"href":"https:\/\/www.crislermusic.com\/index.php\/wp-json\/wp\/v2\/edd-downloads\/2909"}],"collection":[{"href":"https:\/\/www.crislermusic.com\/index.php\/wp-json\/wp\/v2\/edd-downloads"}],"about":[{"href":"https:\/\/www.crislermusic.com\/index.php\/wp-json\/wp\/v2\/types\/download"}],"author":[{"embeddable":true,"href":"https:\/\/www.crislermusic.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/www.crislermusic.com\/index.php\/wp-json\/wp\/v2\/edd-downloads\/2909\/revisions"}],"predecessor-version":[{"id":2950,"href":"https:\/\/www.crislermusic.com\/index.php\/wp-json\/wp\/v2\/edd-downloads\/2909\/revisions\/2950"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.crislermusic.com\/index.php\/wp-json\/wp\/v2\/media\/2921"}],"wp:attachment":[{"href":"https:\/\/www.crislermusic.com\/index.php\/wp-json\/wp\/v2\/media?parent=2909"}],"wp:term":[{"taxonomy":"download_category","embeddable":true,"href":"https:\/\/www.crislermusic.com\/index.php\/wp-json\/wp\/v2\/edd-categories?post=2909"},{"taxonomy":"download_tag","embeddable":true,"href":"https:\/\/www.crislermusic.com\/index.php\/wp-json\/wp\/v2\/edd-tags?post=2909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}